{"id":90726,"date":"2020-11-03T22:25:47","date_gmt":"2020-11-03T22:25:47","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=90726"},"modified":"2020-11-03T22:25:47","modified_gmt":"2020-11-03T22:25:47","slug":"piden-sancionar-alzas-de-precios-de-insumos-medicos-y-medicinas","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/piden-sancionar-alzas-de-precios-de-insumos-medicos-y-medicinas\/","title":{"rendered":"Piden sancionar alzas de precios de insumos m\u00e9dicos y medicinas"},"content":{"rendered":"<p>En Sesi\u00f3n Ordinaria realizada a trav\u00e9s de acceso remoto, el Congreso de Chihuahua exhort\u00f3 a los titulares de la Procuradur\u00eda Federal del Consumidor, a la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios y a la Comisi\u00f3n Estatal para la Protecci\u00f3n Contra Riesgos Sanitarios, a efecto de vigilar,<!--more--> y en su momento sancionar las malas pr\u00e1cticas en el alza de precios en insumos m\u00e9dicos, medicina y equipo de protecci\u00f3n, as\u00ed como la disminuci\u00f3n en la calidad de los productos antes se\u00f1alados.<br \/>\nDe la misma manera se pidi\u00f3 garantizar la equidad y seguridad jur\u00eddica en las relaciones entre proveedores y consumidores dentro del Estado de Chihuahua.<br \/>\nLa propuesta aprobada de manera urgente por integrantes de la Sexag\u00e9sima Sexta Legislatura, fue presentada por el diputado de MORENA, Benjam\u00edn Carrera Ch\u00e1vez, quien se\u00f1al\u00f3 en la exposici\u00f3n, que ante el aumento de contagios por COVID-19, se ha visto un incremento en la demanda de ox\u00edgeno, lo que ha desatado un desabasto y altos precios.<br \/>\nDestac\u00f3 que los nosocomios p\u00fablicos y privados se encuentran saturados para la atenci\u00f3n a pacientes de coronavirus, la demanda de tanques de ox\u00edgeno, medicamentos, cubre bocas, caretas de seguridad y el equipo que utiliza el personal m\u00e9dico, se han elevado al grado que conseguir uno de estos art\u00edculos es complejo para atender a los pacientes en casa.<br \/>\n\u201cEl precio de un tanque de ox\u00edgeno oscila entre los 2 y 7 mil pesos, lo que en promedio equivale a casi 40 d\u00edas de trabajo, es decir el precio es a raz\u00f3n del proveedor, empresas que se dedican a la renta y llenado de ox\u00edgeno medicinal han incrementado a m\u00e1s del triple la venta de este elemento durante el \u00faltimo mes, han hecho de la desgracia una fuente de ingresos, carente de sentido humano\u201d, enfatiz\u00f3 el Legislador.<br \/>\nLa omisi\u00f3n por parte de esta asamblea, as\u00ed como de las autoridades facultadas para la supervisi\u00f3n, calidad de estos productos y en su caso, sanci\u00f3n por la elevaci\u00f3n del precio, pudiera encuadrar en un delito de lesa humanidad, es un asunto que a todos nos interesa y nos responsabiliza sobre el actuar en cada una de los poderes y entes de gobierno, agreg\u00f3 Carrera Ch\u00e1vez.<br \/>\n\u201cSubir exorbitantemente el precio de los insumos m\u00e9dicos, medicina y equipo de protecci\u00f3n es inhumano, un crimen, un atentado contra de la econom\u00eda de las familias. La vida no tiene precio, el gobierno debe garantizar a los habitantes los medicamentos, en el caso m\u00e1s extremo garantizar que estos bienes no sean acaparados y vendidos a precios desproporcionados por particulares\u201d, apuntal\u00f3.<br \/>\nPor otra parte, expres\u00f3 que el sector de m\u00e9dicos, enfermeros y personal de salud, se han visto en la necesidad de adquirir por cuenta propia algunos de los insumos que requieren para el desarrollo de su profesi\u00f3n, ya que los otorgados por sus superiores son m\u00ednimos o de calidades inferiores a las requeridas por su \u00e1rea de trabajo, \u201crecordemos que muchos h\u00e9roes de la salud est\u00e1n en \u00e1reas COVID, donde durante 8 horas no pueden tomar agua, donde deben de portar la protecci\u00f3n necesaria para protegerse y proteger a sus familias\u201d.<br \/>\nEs por lo antes mencionado, que se hace la petici\u00f3n urgente a las autoridades facultadas para garantizar la equidad y seguridad jur\u00eddica en las relaciones entre proveedores y consumidores, act\u00faen y sancionen a quien lucra con el dolor, finaliz\u00f3 el iniciador<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Sesi\u00f3n Ordinaria realizada a trav\u00e9s de acceso remoto, el Congreso de Chihuahua exhort\u00f3 a los titulares de la Procuradur\u00eda Federal del Consumidor, a la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios y a la Comisi\u00f3n Estatal para la Protecci\u00f3n Contra Riesgos Sanitarios, a efecto de vigilar,<\/p>\n","protected":false},"author":5,"featured_media":90715,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-90726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatales"],"views":1,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=90726"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90726\/revisions"}],"predecessor-version":[{"id":90728,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90726\/revisions\/90728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/90715"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=90726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=90726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=90726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}