{"id":90035,"date":"2020-10-27T00:14:53","date_gmt":"2020-10-27T00:14:53","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=90035"},"modified":"2020-10-27T00:14:53","modified_gmt":"2020-10-27T00:14:53","slug":"respalda-blanca-gamez-pronunciamiento-en-defensa-de-la-dignidad-y-la-soberania-del-pueblo-de-chihuahua","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/respalda-blanca-gamez-pronunciamiento-en-defensa-de-la-dignidad-y-la-soberania-del-pueblo-de-chihuahua\/","title":{"rendered":"Respalda Blanca G\u00e1mez pronunciamiento en defensa de la dignidad y la soberan\u00eda del pueblo de Chihuahua"},"content":{"rendered":"<p>La diputada presidenta del Congreso del Estado de Chihuahua Blanca G\u00e1mez Guti\u00e9rrez, respald\u00f3 el Pronunciamiento en defensa de la dignidad y la soberan\u00eda del pueblo de Chihuahua y sus instituciones: \u201cCierre de filas por Chihuahua\u201d, a trav\u00e9s de tres propuestas.<\/p>\n<p>En primer lugar, la legisladora pidi\u00f3 al Gobierno federal solucionar el<!--more--> conflicto del Tratado Internacional de Aguas de 1944, a partir de las propuestas presentadas por productores y el Gobierno del Estado; en segundo termino, plante\u00f3 la reincorporaci\u00f3n del Gobierno de la Rep\u00fablica a la coordinaci\u00f3n en materia de seguridad para garantizar la paz y la tranquilidad de la poblaci\u00f3n .<\/p>\n<p>Y finalmente Blanca G\u00e1mez exigi\u00f3 revisar y corregir el proyecto de Presupuesto de Egresos de la Federaci\u00f3n 2021 para evitar la reducci\u00f3n de recursos del Estado de Chihuahua y en su caso, establecer mecanismos de compensaci\u00f3n presupuestal as\u00ed como revisi\u00f3n de la operaci\u00f3n de los fideicomisos y fondos p\u00fablicos para evitar la extinci\u00f3n de aquellos cuya utilidad est\u00e1 aprobada y en su caso, establecer reglas claras y transparentes para la distribuci\u00f3n de sus recursos.<\/p>\n<p>El evento convocado por la Alianza federalista, tuvo lugar este lunes 26 de octubre en el patio central del palacio de Gobierno, donde se reunieron representantes del sector empresarial, educativo, sociedad civil, c\u00e1maras y sindicatos, personas comisionadas del campo, Movimiento Estatal de Mujeres, alcaldesas y alcaldes, diputadas y diputados locales y federales, sin distinci\u00f3n de partido pol\u00edtico, para exigir al Gobierno federal detenga los recortes presupuestales, la desaparici\u00f3n de fondos p\u00fablicos vitales y las afrentas y descalificaciones que ha hecho en contra de representantes del Estado de Chihuahua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diputada presidenta del Congreso del Estado de Chihuahua Blanca G\u00e1mez Guti\u00e9rrez, respald\u00f3 el Pronunciamiento en defensa de la dignidad y la soberan\u00eda del pueblo de Chihuahua y sus instituciones: \u201cCierre de filas por Chihuahua\u201d, a trav\u00e9s de tres propuestas. En primer lugar, la legisladora pidi\u00f3 al Gobierno federal solucionar el<\/p>\n","protected":false},"author":5,"featured_media":90037,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-90035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatales"],"views":1,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=90035"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90035\/revisions"}],"predecessor-version":[{"id":90038,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/90035\/revisions\/90038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/90037"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=90035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=90035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=90035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}