{"id":45752,"date":"2018-11-22T13:32:45","date_gmt":"2018-11-22T13:32:45","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=45752"},"modified":"2018-11-22T13:32:45","modified_gmt":"2018-11-22T13:32:45","slug":"intensifica-seguridad-publica-programa-de-acompanamiento-bancario","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/intensifica-seguridad-publica-programa-de-acompanamiento-bancario\/","title":{"rendered":"Intensifica Seguridad P\u00fablica Programa de Acompa\u00f1amiento Bancario"},"content":{"rendered":"<p>El Gobierno Municipal, a trav\u00e9s de la Direcci\u00f3n de Seguridad P\u00fablica reitera a la poblaci\u00f3n en general que el Programa de Acompa\u00f1amiento Bancario por parte de agentes de la Polic\u00eda Municipal se ha intensificado con el operativo Escudo Navidad Segura, el cual arranc\u00f3 el pasado 15 de noviembre, considerando que en estas fechas es cuando se realiza la entrega de diversas prestaciones econ\u00f3micas, y en algunas empresas se ven obligadas a realizar operaciones con altas cantidades de dinero en efectivo.<\/p>\n<p>Esta medida preventiva consiste en evitar que tanto empresas como ciudadanos que no cuenten con los recursos para contratar un servicio de<\/p>\n<p><!--more--><\/p>\n<p>vigilancia privada, corran alg\u00fan riesgo mientras realizan los traslados del efectivo, ya sea de su domicilio al banco o viceversa, al momento de realizar los retiros o dep\u00f3sitos.<\/p>\n<p>Asimismo se exhorta a los usuarios de la banca a estar alertas al hacer este tipo de movimientos desde el momento en que salgan de la empresa, vivienda o instituci\u00f3n bancaria y reportar de inmediato al 9-1-1 la presencia de personas sospechosas, igualmente si al salir del banco encuentran su veh\u00edculo con alguna llanta ponchada.<\/p>\n<p>La Polic\u00eda Municipal reitera que el servicio ofrecido a trav\u00e9s del Programa de Acompa\u00f1amiento Bancario es completamente gratuito y los elementos encargados de resguardar a una persona \u00fanicamente preguntar\u00e1n el lugar de destino para hacer algunas recomendaciones de seguridad, sin importar la cantidad de dinero que el usuario lleve consigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Municipal, a trav\u00e9s de la Direcci\u00f3n de Seguridad P\u00fablica reitera a la poblaci\u00f3n en general que el Programa de Acompa\u00f1amiento Bancario por parte de agentes de la Polic\u00eda Municipal se ha intensificado con el operativo Escudo Navidad Segura, el cual arranc\u00f3 el pasado 15 de noviembre, considerando que en estas fechas es cuando [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":45754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-45752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"views":2,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/45752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=45752"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/45752\/revisions"}],"predecessor-version":[{"id":45755,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/45752\/revisions\/45755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/45754"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=45752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=45752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=45752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}