{"id":44485,"date":"2018-11-03T15:12:34","date_gmt":"2018-11-03T15:12:34","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=44485"},"modified":"2018-11-03T15:12:34","modified_gmt":"2018-11-03T15:12:34","slug":"coordinan-dspm-y-tiendas-de-autoservicio-y-departamentales-estrategias-de-seguridad","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/coordinan-dspm-y-tiendas-de-autoservicio-y-departamentales-estrategias-de-seguridad\/","title":{"rendered":"Coordinan DSPM y tiendas de autoservicio y departamentales estrategias de seguridad"},"content":{"rendered":"<p>Directivos de Seguridad P\u00fablica Municipal y miembros de la Asociaci\u00f3n Nacional de Tiendas de Autoservicio y Departamentales (ANTAD), se reunieron con el fin de afinar la estrategia que habr\u00e1 de aplicarse como parte del operativo anual de fin de a\u00f1o para el sector comercial y que comprende diversas acciones para evitar, entre otros, delitos como el robo fardero al interior de las tiendas y al exterior en estacionamientos de veh\u00edculos.<\/p>\n<p>La reuni\u00f3n de trabajo se desarroll\u00f3 en las instalaciones de la Comandancia Norte donde representantes de cadenas de tiendas como Wal Mart, Smart, Soriana, Oxxo, Al Super, Woolworth, Liverpool, F\u00e1bricas de Francia, Lowe\u2019s, Coppel y Sanborn\u00b4s acordaron con personal del Departamento Operativo y del \u00e1rea de<\/p>\n<p><!--more--><\/p>\n<p>Prevenci\u00f3n de la Polic\u00eda Municipal acciones de vigilancia con polic\u00edas y cadetes para prevenir incidentes en los mismos establecimientos y con los miles de compradores que los frecuentan durante la temporada de mayor derrama econ\u00f3mica.<\/p>\n<p>El operativo comprende la instalaci\u00f3n del Centro de Mando M\u00f3vil en los diversos centros y avenidas comerciales para coordinar las acciones de los elementos asignados a la estrategia, as\u00ed como la utilizaci\u00f3n del Halc\u00f3n 1 y las c\u00e1maras de la Plataforma Escudo Chihuahua como una acci\u00f3n de seguridad integral para el comercio y sus clientes.<\/p>\n<p>Cabe mencionar que si bien estas dos instituciones realizan sesiones ordinarias cada mes, en esta ocasi\u00f3n la mesa tuvo car\u00e1cter de extraordinaria ante la proximidad de ventas masivas derivadas de la puesta en marcha de ofertas y promociones como el Buen Fin y algunas otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Directivos de Seguridad P\u00fablica Municipal y miembros de la Asociaci\u00f3n Nacional de Tiendas de Autoservicio y Departamentales (ANTAD), se reunieron con el fin de afinar la estrategia que habr\u00e1 de aplicarse como parte del operativo anual de fin de a\u00f1o para el sector comercial y que comprende diversas acciones para evitar, entre otros, delitos como [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":44487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-44485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"views":6,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=44485"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44485\/revisions"}],"predecessor-version":[{"id":44488,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44485\/revisions\/44488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/44487"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=44485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=44485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=44485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}