{"id":44415,"date":"2018-11-03T14:06:36","date_gmt":"2018-11-03T14:06:36","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=44415"},"modified":"2018-11-03T14:06:36","modified_gmt":"2018-11-03T14:06:36","slug":"propone-geo-bujanda-fondo-subsidiario-de-seguridad-publica-municipal","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/propone-geo-bujanda-fondo-subsidiario-de-seguridad-publica-municipal\/","title":{"rendered":"Propone Geo Bujanda Fondo Subsidiario de Seguridad P\u00fablica Municipal"},"content":{"rendered":"<p>La Presidenta de la Comisi\u00f3n de Seguridad P\u00fablica en el Congreso, Georgina Bujanda, present\u00f3 iniciativa para crear el Fondo Subsidiario de Seguridad P\u00fablica Municipal, con el cual busca que el estado destine recursos a los municipios que no son beneficiados con recursos federales, como el Fondo de Aportaciones para la Seguridad P\u00fablica (FASP).<\/p>\n<p>Bujanda se\u00f1al\u00f3 que en el ejercicio fiscal 2018, el Estado de Chihuahua, s\u00f3lo tiene como beneficiarios de recursos federales destinados a seguridad p\u00fablica a los municipios de Camargo, Chihuahua, Cuauht\u00e9moc, Delicias, Hidalgo del Parral, Ju\u00e1rez y Meoqui, no que as\u00ed al resto de los 60 municipios, por lo que<\/p>\n<p><!--more--><\/p>\n<p>se ven imposibilitados de equipar y capacitar a sus respectivas corporaciones de polic\u00eda municipal. Derivado de lo anterior , la necesidad de crear este fondo, el cual contar\u00e1 con par\u00e1metros t\u00e9cnico objetivos para la asignaci\u00f3n y\/o elegibilidad del monto de los recursos a los municipios que cumplan con las reglas de operaci\u00f3n que establezca el Ejecutivo estatal a trav\u00e9s de la Secretaria de Hacienda.<\/p>\n<p>Lo que se busca con el Fondo Subsidiario de Seguridad P\u00fablica Municipal es transformar la pol\u00edtica de seguridad hacia una de aut\u00e9ntica coordinaci\u00f3n entre \u00f3rdenes de gobierno estatal y municipal, que asigne los recursos que nos permitan el fortalecimiento de las instituciones m\u00e1s cercanas a la ciudadan\u00eda y por lo tanto, tambi\u00e9n a la prevenci\u00f3n y a la reacci\u00f3n, empezando por la existencia de una suficiencia presupuestal, para garantizar a las y los polic\u00edas un proyecto digno de vida a trav\u00e9s de su carrera. Por ello, los principales factores a tomar en cuenta sean la capacitaci\u00f3n, que necesariamente debe ir ligada a todo un planteamiento de profesionalizaci\u00f3n, y dignificaci\u00f3n policial, as\u00ed como a reforzar los controles de confianza, puntualiz\u00f3 la diputada panista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta de la Comisi\u00f3n de Seguridad P\u00fablica en el Congreso, Georgina Bujanda, present\u00f3 iniciativa para crear el Fondo Subsidiario de Seguridad P\u00fablica Municipal, con el cual busca que el estado destine recursos a los municipios que no son beneficiados con recursos federales, como el Fondo de Aportaciones para la Seguridad P\u00fablica (FASP). Bujanda se\u00f1al\u00f3 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":44417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-44415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"views":35,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=44415"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44415\/revisions"}],"predecessor-version":[{"id":44418,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/44415\/revisions\/44418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/44417"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=44415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=44415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=44415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}