{"id":43900,"date":"2018-10-27T15:45:37","date_gmt":"2018-10-27T15:45:37","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=43900"},"modified":"2018-10-27T15:45:37","modified_gmt":"2018-10-27T15:45:37","slug":"destaca-usaid-programa-de-prevencion-de-asociacion-chihuahuense","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/destaca-usaid-programa-de-prevencion-de-asociacion-chihuahuense\/","title":{"rendered":"Destaca USAID programa de prevenci\u00f3n de asociaci\u00f3n chihuahuense"},"content":{"rendered":"<p>Con una puntuaci\u00f3n de 107 de 120 posibles, la Red de Cohesi\u00f3n y Participaci\u00f3n Social, 1, 2, 3, por m\u00ed y por mi Comunidad A.C., fue reconocida por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), como practica promisoria para la implementaci\u00f3n de acciones a favor de la prevenci\u00f3n de la violencia entre los j\u00f3venes.<\/p>\n<p>Lo anterior, tras la aplicaci\u00f3n de la Escala de Buenas Pr\u00e1cticas (EBP) de USAID, donde se realiz\u00f3 una evaluaci\u00f3n que consisti\u00f3 en diagn\u00f3stico, respaldo te\u00f3rico, planeaci\u00f3n, implementaci\u00f3n y resultados de las actividades que realiza la asociaci\u00f3n civil en cinco espacios p\u00fablicos de la ciudad con el apoyo de la<\/p>\n<p><!--more--><\/p>\n<p>Fundaci\u00f3n del Empresariado Chihuahuense (FECHAC).<\/p>\n<p>El logro por parte de la Red de Cohesi\u00f3n y Participaci\u00f3n Social, 1, 2, 3, por m\u00ed y por mi Comunidad, fue posible tras la aplicaci\u00f3n Juntos para la Prevenci\u00f3n de la Violencia (JPV), el cual tiene como objetivo principal el de contribuir a la disminuci\u00f3n de los delitos a trav\u00e9s del fortalecimiento de las capacidades de adaptaci\u00f3n e implementaci\u00f3n de los sistemas locales.<\/p>\n<p>Dentro de los par\u00e1metros que estableci\u00f3 el organismo internacional para otorgar dicho puntaje, fue la valoraci\u00f3n del modelo de intervenci\u00f3n comunitaria con perspectiva de j\u00f3venes que realiza la asociaci\u00f3n chihuahuense, en el cual se realizan una serie de acciones estrat\u00e9gicas que van desde pl\u00e1ticas, talleres, eventos culturales y sociales, lo que ha contribuido de manera considera a un mejor entorno, todo con el respaldo de la FECHAC.<\/p>\n<p>La Escala de Buenas Pr\u00e1cticas por parte de USAID, forma parte de un mecanismo internacional que se suma a esfuerzos de numerosas organizaciones acad\u00e9micas y de desarrollo internacional que promueven el uso y la generaci\u00f3n de evidencia para la toma de decisiones p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una puntuaci\u00f3n de 107 de 120 posibles, la Red de Cohesi\u00f3n y Participaci\u00f3n Social, 1, 2, 3, por m\u00ed y por mi Comunidad A.C., fue reconocida por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), como practica promisoria para la implementaci\u00f3n de acciones a favor de la prevenci\u00f3n de la violencia [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":43902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-43900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"views":53,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/43900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=43900"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/43900\/revisions"}],"predecessor-version":[{"id":43903,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/43900\/revisions\/43903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/43902"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=43900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=43900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=43900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}