{"id":23887,"date":"2017-12-12T21:39:37","date_gmt":"2017-12-12T21:39:37","guid":{"rendered":"http:\/\/notitodo.com.mx\/wp\/?p=23887"},"modified":"2017-12-12T21:39:37","modified_gmt":"2017-12-12T21:39:37","slug":"pide-javier-corral-audiencia-en-el-senado-para-exponer-contra-la-ley-de-seguridad-interior","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/pide-javier-corral-audiencia-en-el-senado-para-exponer-contra-la-ley-de-seguridad-interior\/","title":{"rendered":"PIDE JAVIER CORRAL AUDIENCIA EN EL SENADO PARA EXPONER CONTRA LA LEY DE SEGURIDAD INTERIOR"},"content":{"rendered":"<p>El Gobernador Javier Corral Jurado solicit\u00f3 al Senado de la Rep\u00fablica una audiencia para exponer sus observaciones respecto a la Ley de Seguridad Interior, con el \u00e1nimo, dijo el mandatario estatal, de que se corrija y realmente le sirva al pa\u00eds.<\/p>\n<p><!--more--><\/p>\n<p>Mediante un oficio enviado a la C\u00e1mara Alta, pidi\u00f3 reunirse con senadores integrantes de las comisiones Unidas de Gobernaci\u00f3n, de Defensa Nacional, de Marina, de Seguridad P\u00fablica y de Puntos Constitucionales, pues considera que debe haber una discusi\u00f3n m\u00e1s amplia sobre el tema y, sobre todo, corregir la narrativa de la misma.<\/p>\n<p>El mandatario estatal afirm\u00f3 que como est\u00e1 dise\u00f1ada en estos momentos, la Ley de Seguridad Interior es de mucho riesgo para la sociedad en general y para el conjunto de las libertades en el pa\u00eds, incluida la labor de los comunicadores.<\/p>\n<p>\u201cLo que se necesita \u2013indic\u00f3\u2013 es un marco que regule la actividad de colaboraci\u00f3n y no una ley que termine militarizando la seguridad p\u00fablica\u201d.<\/p>\n<p>En entrevista con los medios de comunicaci\u00f3n, se\u00f1al\u00f3 que hay voces de organismos internacionales de derechos humanos, activistas y juristas de mucho prestigio que han llamado a la serenidad y a la prudencia a los legisladores.<\/p>\n<p>Consider\u00f3 que el principal problema del proyecto es la ambig\u00fcedad del lenguaje, \u201cuna redacci\u00f3n ambigua que no debe darse en una materia como es la seguridad p\u00fablica\u201d.<\/p>\n<p>El mandatario aclar\u00f3 que tampoco se trata de desconocer el trabajo de las Fuerzas Armadas o de decir que ya deben irse, porque no hay un solo gobernador que pueda renunciar a su colaboraci\u00f3n.<\/p>\n<p>\u201cYo mismo he pedido la presencia de las Fuerzas Armadas en el Estado de Chihuahua, pero en un esquema de colaboraci\u00f3n con la autoridad civil, de cooperaci\u00f3n, no en una sustituci\u00f3n\u201d, expres\u00f3.<\/p>\n<p>Corral Jurado, a\u00f1adi\u00f3 que su propuesta es apostarle a la polic\u00eda con profesionalizaci\u00f3n, capacitaci\u00f3n, con una depuraci\u00f3n donde se apliquen controles de confianza y con la generaci\u00f3n de mecanismos de inteligencia policial.<\/p>\n<p>En la actualidad, agreg\u00f3, el problema de la inseguridad en el pa\u00eds es muy delicado, por eso se permanece en una pol\u00edtica de contenci\u00f3n, cuando lo ideal ser\u00eda una pol\u00edtica de inteligencia policial, donde los recursos se destinen m\u00e1s a sistemas de an\u00e1lisis e inteligencia que de fuerza.<\/p>\n<p>Destac\u00f3 que hay casos como el de Ju\u00e1rez, donde lo que se hace en primer lugar es compartir informaci\u00f3n \u201cpero la estrategia clave en materia de seguridad se llama coordinaci\u00f3n honesta e imparcial entre autoridades\u201d.<\/p>\n<p>Javier Corral propuso que el tema de la seguridad p\u00fablica sea de neutralidad pol\u00edtica, donde no haya medro pol\u00edtico para atacar al adversario o disputarse el m\u00e9rito, cuando la realidad, los resultados son labor de todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador Javier Corral Jurado solicit\u00f3 al Senado de la Rep\u00fablica una audiencia para exponer sus observaciones respecto a la Ley de Seguridad Interior, con el \u00e1nimo, dijo el mandatario estatal, de que se corrija y realmente le sirva al pa\u00eds.<\/p>\n","protected":false},"author":5,"featured_media":23888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-23887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatales"],"views":49,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/23887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=23887"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/23887\/revisions"}],"predecessor-version":[{"id":23889,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/23887\/revisions\/23889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/23888"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=23887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=23887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=23887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}