{"id":128154,"date":"2025-11-02T00:17:43","date_gmt":"2025-11-02T06:17:43","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=128154"},"modified":"2025-11-04T01:06:25","modified_gmt":"2025-11-04T07:06:25","slug":"celebran-el-dia-de-muertos-en-instituciones-educativas-de-chihuahua","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/celebran-el-dia-de-muertos-en-instituciones-educativas-de-chihuahua\/","title":{"rendered":"Celebran el D\u00eda de Muertos en instituciones educativas de Chihuahua"},"content":{"rendered":"<p>Instituciones educativas de todos los niveles celebraron el D\u00eda de Muertos con una serie de actividades en las que participaron docentes, estudiantes, madres y padres de familia, con el objetivo de preservar y fomentar los valores y tradiciones mexicanas.<\/p>\n<p>El Colegio de Educaci\u00f3n Profesional T\u00e9cnica (Conalep) llev\u00f3 a cabo diversas din\u00e1micas en sus planteles y<!--more--> extensiones acad\u00e9micas, que incluyeron concursos de altares de muertos, catrinas y catrines.<\/p>\n<p>Adem\u00e1s, en el Plantel Parral se realiz\u00f3 un desfile, y en Delicias se permiti\u00f3 al alumnado acudir disfrazado a clases.<\/p>\n<p>Las alumnas y los alumnos del Colegio de Bachilleres del Estado de Chihuahua (Cobach), montaron coloridos altares en sus planteles y dieron muestra de su creatividad con detallados disfraces de catrinas y catrines.<\/p>\n<p>La Escuela de Trabajo Social \u201cProfra. y T.S. Guadalupe S\u00e1nchez de Araiza\u201d, realiz\u00f3 el Festival del D\u00eda de Muertos 2025, una jornada llena de tradici\u00f3n, color y alegr\u00eda, con altares, concurso de catrinas y la exposici\u00f3n de tumbas \u201cEl Pante\u00f3n de las Memorias\u201d, elaborada por el personal de la instituci\u00f3n.<\/p>\n<p>Con el tema de la leyenda del famoso sal\u00f3n de baile \u201cEl Carrusel\u201d, el Colegio de Chihuahua particip\u00f3 en \u201cRa\u00edces y Recuerdos, Pante\u00f3n de las \u00c1nimas\u201d, organizado por el Gobierno del Estado.<\/p>\n<p>En la Universidad Polit\u00e9cnica de Chihuahua (UPCH), el alumnado realiz\u00f3 altares en memoria de Roberto G\u00f3mez Bola\u00f1os \u201cChespirito\u201d, Mario Moreno \u201cCantinflas\u201d, Homero G\u00f3mez Gonz\u00e1lez, Guillermo Gonz\u00e1lez Camarena, Ram\u00f3n Valdiosera y Jenni Rivera, donde se reflej\u00f3 el talento, la creatividad y el trabajo colaborativo.<\/p>\n<p>La Universidad Tecnol\u00f3gica de la Bab\u00edcora (UTB) organiz\u00f3 un Festival de D\u00eda de Muertos con concursos de catrinas gigantes y de caracterizaci\u00f3n de catrines, participaciones art\u00edsticas de canto y declamaci\u00f3n, adem\u00e1s de un convivio con comida t\u00edpica.<\/p>\n<p>En la Universidad Tecnol\u00f3gica de Parral (UTP) se mont\u00f3 una exposici\u00f3n de altares de muertos, tanto en el campus sede como en la unidad acad\u00e9mica de Balleza, con la participaci\u00f3n activa de alumnas y alumnos caracterizados.<\/p>\n<p>La Universidad Tecnol\u00f3gica de Ciudad Ju\u00e1rez (UTCJ) celebr\u00f3 con la instalaci\u00f3n de puestos de comida tradicional, venta de artesan\u00edas y una variada programaci\u00f3n art\u00edstica.<\/p>\n<p>Con estas acciones se busc\u00f3 fomentar la cultura, las tradiciones mexicanas y la participaci\u00f3n en los diferentes niveles acad\u00e9micos de toda la entidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instituciones educativas de todos los niveles celebraron el D\u00eda de Muertos con una serie de actividades en las que participaron docentes, estudiantes, madres y padres de familia, con el objetivo de preservar y fomentar los valores y tradiciones mexicanas. El Colegio de Educaci\u00f3n Profesional T\u00e9cnica (Conalep) llev\u00f3 a cabo diversas din\u00e1micas en sus planteles y<\/p>\n","protected":false},"author":5,"featured_media":128156,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-128154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"views":15,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/128154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=128154"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/128154\/revisions"}],"predecessor-version":[{"id":128157,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/128154\/revisions\/128157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/128156"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=128154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=128154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=128154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}