{"id":126893,"date":"2024-09-14T13:59:39","date_gmt":"2024-09-14T19:59:39","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=126893"},"modified":"2024-09-15T14:02:44","modified_gmt":"2024-09-15T20:02:44","slug":"participan-mas-de-1500-personas-en-carrera-de-colores-de-la-utch","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/participan-mas-de-1500-personas-en-carrera-de-colores-de-la-utch\/","title":{"rendered":"Participan m\u00e1s de 1,500 personas en carrera de colores de la UTCH"},"content":{"rendered":"<p>La Universidad Tecnol\u00f3gica de Chihuahua (UTCH) mantiene el firme compromiso de brindar al estudiante una educaci\u00f3n integral a trav\u00e9s de actividades c\u00edvicas, culturales y deportivas, por ello se realiz\u00f3 la tradicional carrera de colores para el cuatrimestre septiembre-diciembre de 2024.<\/p>\n<p>Esta carrera, tambi\u00e9n conocida como \u201ccarrera de bienvenida de colores\u201d, cuenta con la participaci\u00f3n de las alumnas y alumnos de nuevo ingreso, pero queda abierta a todos aquellos que<!--more--> tambi\u00e9n deseen sumarse.<\/p>\n<p>Previo al arranque se tuvo una activaci\u00f3n f\u00edsica masiva, posteriormente, las y los participantes realizaron un recorrido de 2 kil\u00f3metros, partiendo de la rotonda de la entrada a la instituci\u00f3n, siguiendo por todo el circuito que abarca el per\u00edmetro de las instalaciones de la UTCH, para finalizar en el punto de inicio.<\/p>\n<p>Al t\u00e9rmino de la carrera, los directivos de la Universidad llevaron a cabo la premiaci\u00f3n de los tres primeros lugares de las dos categor\u00edas: Estudiantes en general, y Docentes y administrativos, en las ramas varonil y femenil.<\/p>\n<p>Lo que hace particular a esta carrera, es que se tienen estaciones de polvos de colores, los cuales hacen que el evento se pinte de alegr\u00eda, y a su vez, es un incentivo para los corredores el ir llegando a las estaciones de color.<\/p>\n<p>En esta ocasi\u00f3n se cont\u00f3 con la participaci\u00f3n de m\u00e1s de mil 500 estudiantes, docentes y administrativos, quienes se mostraron muy entusiastas y disfrutaron del evento.<\/p>\n<p>Para mayor informaci\u00f3n sobre las actividades culturales y deportivas de la UTCH, se puede llamar al tel\u00e9fono 614-432-20-00 extensiones 1145 y 1185.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Tecnol\u00f3gica de Chihuahua (UTCH) mantiene el firme compromiso de brindar al estudiante una educaci\u00f3n integral a trav\u00e9s de actividades c\u00edvicas, culturales y deportivas, por ello se realiz\u00f3 la tradicional carrera de colores para el cuatrimestre septiembre-diciembre de 2024. Esta carrera, tambi\u00e9n conocida como \u201ccarrera de bienvenida de colores\u201d, cuenta con la participaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":126895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-126893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"views":3,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/126893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=126893"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/126893\/revisions"}],"predecessor-version":[{"id":126896,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/126893\/revisions\/126896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/126895"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=126893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=126893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=126893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}