{"id":122464,"date":"2023-11-21T01:00:47","date_gmt":"2023-11-21T01:00:47","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=122464"},"modified":"2023-11-21T01:00:47","modified_gmt":"2023-11-21T01:00:47","slug":"se-corona-ut-de-camargo-como-campeona-del-circuito-estatal-de-beisbol-universitario","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/se-corona-ut-de-camargo-como-campeona-del-circuito-estatal-de-beisbol-universitario\/","title":{"rendered":"Se corona UT de Camargo como campeona del  Circuito Estatal de Beisbol Universitario"},"content":{"rendered":"<p>La Universidad Tecnol\u00f3gica de Camargo (UTCam) se coron\u00f3 como campeona del primer Circuito Estatal de Beisbol Universitario de Chihuahua, al derrotar en la final al conjunto del Instituto Tecnol\u00f3gico de Delicias.<\/p>\n<p>El partido final se efectu\u00f3 en el Gran Estadio de Delicias, donde los Vaqueros de la<!--more--> Universidad Tecnol\u00f3gica de Camargo se impusieron 4 a 1 ante los Halcones del Instituto Tecnol\u00f3gico de Delicias.<\/p>\n<p>El rector de la UTCam, Jos\u00e9 Julio Huerta Herrera, felicit\u00f3 al representativo universitario y se dijo orgulloso de sus logros, ya que dieron todo en el campo y es el resultado de la entrega y dedicaci\u00f3n que muestran d\u00eda con d\u00eda.<\/p>\n<p>De igual manera, reconoci\u00f3 el trabajo de los entrenadores de la selecci\u00f3n de beisbol de la Universidad, por la motivaci\u00f3n y cohesi\u00f3n que transmiten al equipo.<\/p>\n<p>El primer Circuito Estatal de Beisbol Universitario de Chihuahua fue organizado por la Secretar\u00eda de Educaci\u00f3n y Deporte (SEyD), en el marco de las acciones de la estrategia \u201cJuntos por tu Futuro\u201d, y con el objetivo de fomentar la actividad f\u00edsica como parte del desarrollo integral del estudiantado.<\/p>\n<p>En la justa deportiva se cont\u00f3 con la participaci\u00f3n de equipos de instituciones de Educaci\u00f3n Superior de las diferentes regiones de la entidad, en la cual adem\u00e1s de promover el deporte se fortalecieron valores como la colaboraci\u00f3n, la disciplina, el trabajo en equipo, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Tecnol\u00f3gica de Camargo (UTCam) se coron\u00f3 como campeona del primer Circuito Estatal de Beisbol Universitario de Chihuahua, al derrotar en la final al conjunto del Instituto Tecnol\u00f3gico de Delicias. El partido final se efectu\u00f3 en el Gran Estadio de Delicias, donde los Vaqueros de la<\/p>\n","protected":false},"author":5,"featured_media":122466,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-122464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"views":45,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/122464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=122464"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/122464\/revisions"}],"predecessor-version":[{"id":122467,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/122464\/revisions\/122467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/122466"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=122464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=122464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=122464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}