{"id":120149,"date":"2023-05-31T20:26:28","date_gmt":"2023-05-31T20:26:28","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=120149"},"modified":"2023-05-31T20:26:28","modified_gmt":"2023-05-31T20:26:28","slug":"participan-estudiantes-de-educacion-especial-en-convivencia-deportiva-en-aldama","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/participan-estudiantes-de-educacion-especial-en-convivencia-deportiva-en-aldama\/","title":{"rendered":"Participan estudiantes de Educaci\u00f3n Especial en  convivencia deportiva en Aldama"},"content":{"rendered":"<p>Estudiantes de Educaci\u00f3n Especial de la Zona Escolar No. 16 celebraron una gran convivencia deportiva celebraron en el Estadio Municipal de F\u00fatbol V\u00edctor Manuel Alba Rojo en ciudad Aldama, donde compitieron en atletismo, lanzamiento de bala y de pelota, as\u00ed como carreras asistidas en silla de ruedas.<\/p>\n<p>La ceremonia de inauguraci\u00f3n inici\u00f3 con la presentaci\u00f3n de los grupos representativos de los <!--more-->Centros de Atenci\u00f3n M\u00faltiple (CAM) y las Unidades de Servicios de Apoyo a la Educaci\u00f3n Regular (USAER), los cuales estuvieron acompa\u00f1ados por sus docentes y sus familias.<\/p>\n<p>Las y los deportistas participantes pertenecen a los CAM No.3, No.9, No.23 y No.40, adem\u00e1s del USAER 200X y mostraron gran entusiasmo durante su participaci\u00f3n en la justa deportiva.<\/p>\n<p>Los honores a los s\u00edmbolos patrios estuvieron a cargo de la Banda y Escolta de Bandera de la Escuela Primaria Rafael Molina Betancourt, bajo la direcci\u00f3n del profesor Gregorio Pay\u00e1n.<\/p>\n<p>El pres\u00eddium del evento estuvo integrado por el alcalde de Aldama, Miguel Rubio Castillo; la presidenta del DIF Municipal, Brenda Porras Venegas; la jefa del Departamento de Educaci\u00f3n F\u00edsica de Servicios Educativos del Estado de Chihuahua (SEECH), Cinthia Arenales Ram\u00edrez; entre otras personalidades.<\/p>\n<p>En su mensaje inaugural, el alcalde expres\u00f3 su agradecimiento a las y los docentes, y felicit\u00f3 a las madres y padres de familia que trabajan d\u00eda a d\u00eda para sacar adelante a sus hijas e hijos, adem\u00e1s se comprometi\u00f3 a seguir trabajando para colaborar con la Zona Escolar No.16 en acciones que beneficien al alumnado de Educaci\u00f3n Especial, con proyectos que les permitan desarrollarse m\u00e1s all\u00e1 de las aulas.<\/p>\n<p>Al final de la convivencia, cada estudiante recibi\u00f3 una medalla de participaci\u00f3n, as\u00ed como los aplausos y porras del p\u00fablico asistente al evento, que apoy\u00f3 en cada momento desde las gradas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes de Educaci\u00f3n Especial de la Zona Escolar No. 16 celebraron una gran convivencia deportiva celebraron en el Estadio Municipal de F\u00fatbol V\u00edctor Manuel Alba Rojo en ciudad Aldama, donde compitieron en atletismo, lanzamiento de bala y de pelota, as\u00ed como carreras asistidas en silla de ruedas. La ceremonia de inauguraci\u00f3n inici\u00f3 con la presentaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":120151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-120149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"views":8,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/120149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=120149"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/120149\/revisions"}],"predecessor-version":[{"id":120152,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/120149\/revisions\/120152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/120151"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=120149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=120149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=120149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}