{"id":103585,"date":"2022-02-08T16:50:30","date_gmt":"2022-02-08T16:50:30","guid":{"rendered":"https:\/\/notitodo.com.mx\/wp\/?p=103585"},"modified":"2022-03-02T01:51:18","modified_gmt":"2022-03-02T01:51:18","slug":"mexico-cuenta-con-un-sistema-electoral-solido-y-robusto-que-no-debe-reinventarse-lorenzo-cordova","status":"publish","type":"post","link":"https:\/\/notitodo.com.mx\/wp\/mexico-cuenta-con-un-sistema-electoral-solido-y-robusto-que-no-debe-reinventarse-lorenzo-cordova\/","title":{"rendered":"M\u00e9xico cuenta con un sistema electoral s\u00f3lido y robusto que no debe reinventarse: Lorenzo C\u00f3rdova"},"content":{"rendered":"<ul type=\"disc\">\n<li class=\"x_x_MsoListParagraphCxSpFirst\"><b><i>Una eventual reforma electoral requiere de amplios consensos pol\u00edticos, se\u00f1al\u00f3 en un foro organizado por senadores de Morena<\/i><\/b><\/li>\n<li class=\"x_x_MsoListParagraphCxSpMiddle\"><b><i>El sistema electoral vigente puede garantizar certeza a los comicios de 2024<\/i><\/b><\/li>\n<li class=\"x_x_MsoListParagraphCxSpLast\"><b><i>Presenta 6 ejes claves hacia una reforma electoral<\/i><\/b><\/li>\n<\/ul>\n<p class=\"x_x_MsoNormal\">M\u00e9xico cuenta con sistema electoral robusto, s\u00f3lido y con gran reconocimiento internacional que, si bien es mejorable, debe avanzar hacia su consolidaci\u00f3n y no hacia su reinvenci\u00f3n, asegur\u00f3 el Consejero Presidente del Instituto Nacional Electoral (INE), Lorenzo C\u00f3rdova Vianello.<\/p>\n<p class=\"x_x_MsoNormal\">Durante su participaci\u00f3n en el Foro Reforma Pol\u00edtica en la Cuarta Transformaci\u00f3n, organizado por el senador Jos\u00e9 Narro C\u00e9spedes, alert\u00f3 del riesgo que implica una eventual reforma que pueda ir en contra de la lucha hist\u00f3rica para consolidar un sistema democr\u00e1tico en M\u00e9xico.<\/p>\n<p class=\"x_x_MsoNormal\">\u201cLo que funciona no se arregla porque se puede descomponer. Yo creo que s\u00ed hay que mejorar nuestro sistema electoral, pero bajo la premisa de que es un sistema perfectible que no hay que reinventar. Reconozcamos lo que hemos hecho y apostemos a mejorarlo, pero no a tirar, como suele decirse, el ni\u00f1o con el agua sucia\u201d, sentenci\u00f3.<\/p>\n<p class=\"x_x_MsoNormal\">El Consejero Presidente afirm\u00f3 que hoy se cuenta con un sistema donde se respeta el voto, donde la equidad en las condiciones de la competencia se ha logrado arduamente y, sobre todo, donde existe un blindaje respecto a la intromisi\u00f3n que en el pasado ten\u00edan los medios de comunicaci\u00f3n poniendo candidatos y definiendo la ruta de los destinos electorales.<\/p>\n<p class=\"x_x_MsoNormal\">Al detallar cada una de las reformas que se han producido a lo largo de 30 a\u00f1os, C\u00f3rdova Vianello destac\u00f3 la importancia de que un eventual cambio legislativo tambi\u00e9n cuente con un amplio respaldo de todas las fuerzas pol\u00edticas y no por una impositiva mayor\u00eda, porque puede haber problemas.<\/p>\n<p class=\"x_x_MsoNormal\">\u201cCuando las reglas no son producto del consenso, siempre va a haber alguien que se va a decir lastimado y que va a acusar que las reglas no eran justas. Cuando la designaci\u00f3n de las autoridades electorales no es producto del m\u00e1s amplio consenso, ya lo vivimos y eso gener\u00f3 un problema y se puede abrir un problema pol\u00edticamente muy delicado\u201d, agreg\u00f3.<\/p>\n<p class=\"x_x_MsoNormal\">En este sentido, garantiz\u00f3 que los comicios presidenciales del 2024 pueden celebrarse bajo el actual sistema, el mismo que permiti\u00f3 la organizaci\u00f3n de los comicios con mayor solidez t\u00e9cnica como los de 2018, as\u00ed como los de mayor participaci\u00f3n que fueron los del 2021.<\/p>\n<p class=\"x_x_MsoNormal\"><b><i>Presenta seis ejes de cara a una eventual reforma electoral<\/i><\/b><\/p>\n<p class=\"x_x_MsoNormal\">El Consejero Presidente celebr\u00f3 la realizaci\u00f3n de este tipo de debates y present\u00f3 seis ejes centrales que deben ser considerados de cara a una eventual reforma que busque mejorar al sistema electoral.<\/p>\n<p class=\"x_x_MsoNormal\">Primero, la reforma tiene que servir para mejorar y perfeccionar el sistema representativo que tenemos; de lo contrario, no vale la pena, ya que el objetivo debe ser apostar para que el Congreso refleje de la mejor manera el pluralismo de nuestra sociedad.<\/p>\n<p class=\"x_x_MsoNormal\">En segundo lugar, habl\u00f3 del financiamiento p\u00fablico como una de las grandes conquistas del sistema electoral, por lo que no basta s\u00f3lo con reducir o cerrar la llave, ya que puede ser una gran equivocaci\u00f3n que puede llevar a los partidos a buscar recursos donde no queremos o incluso se puede abrir la puerta a intereses corporativos.<\/p>\n<p class=\"x_x_MsoNormal\">El alto costo de los procesos electorales, se\u00f1al\u00f3 como tercer punto, es producto de la desconfianza ciudadana, por lo que su abaratamiento camina hacia el voto electr\u00f3nico, el cual el INE ya implementa por la v\u00eda de las urnas electr\u00f3nicas y mediante un sistema por internet s\u00f3lido.<\/p>\n<p class=\"x_x_MsoNormal\">Respecto a la justicia electoral, el cuarto aspecto, el Consejero Presidente consider\u00f3 necesario abrir la informaci\u00f3n por parte de las autoridades ministeriales, como es el caso de Odebrecht, ya que hasta el momento la Fiscal\u00eda General de la Rep\u00fablica ha negado el acceso a las carpetas de investigaci\u00f3n; as\u00ed como considerar la necesidad de que las medidas cautelares salgan completamente del INE.<\/p>\n<p class=\"x_x_MsoNormal\">En quinto lugar, dijo, se debe simplificar el sistema, ya que hay demasiadas previsiones que el INE debe cumplir, as\u00ed como prohibiciones a los actores pol\u00edticos. Claro ejemplo de ello es el absurdo que impide a los partidos pronunciarse en el tema de la Revocaci\u00f3n de Mandato.<\/p>\n<p class=\"x_x_MsoNormal\">\u201cPero no es el INE, es el dise\u00f1o legal y tenemos que simplificarlo\u201d.<\/p>\n<p class=\"x_x_MsoNormal\">Por \u00faltimo, enfatiz\u00f3 en la importancia de que las medidas afirmativas que se han instrumentado desde el INE sean adoptadas a nivel legislativo y, con ello, corregir y hasta mejorar algunas incongruencias como que haya representaci\u00f3n migrante en el Congreso, pero no se permita el voto de las y los mexicanos en el extranjero.<\/p>\n<p class=\"x_x_MsoNormal\">El Foro cont\u00f3 con la presencia de la Presidenta de la Mesa Directiva del Senado de la Rep\u00fablica, Olga S\u00e1nchez Cordero; los senadores de Morena, Antares Guadalupe V\u00e1zquez Alatorre y Ovidio Peralta Su\u00e1rez, as\u00ed como la Secretaria General de Morena, Citlalli Hern\u00e1ndez.<\/p>\n<p class=\"x_x_MsoNormal\">Tambi\u00e9n participaron el Secretario de Comunicaci\u00f3n, Difusi\u00f3n y Propaganda de Morena, Diego Alberto Hern\u00e1ndez Guti\u00e9rrez; el ex senador, Raymundo C\u00e1rdenas Hern\u00e1ndez, y el presidente de la Asociaci\u00f3n de Tribunales y Salas Electorales de la Rep\u00fablica Mexicana, Cesar Lorenzo Wong Meraz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una eventual reforma electoral requiere de amplios consensos pol\u00edticos, se\u00f1al\u00f3 en un foro organizado por senadores de Morena El sistema electoral vigente puede garantizar certeza a los comicios de 2024 Presenta 6 ejes claves hacia una reforma electoral M\u00e9xico cuenta con sistema electoral robusto, s\u00f3lido y con gran reconocimiento internacional que, si bien es mejorable, [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":103590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-103585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatales"],"views":10,"_links":{"self":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/103585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/comments?post=103585"}],"version-history":[{"count":1,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/103585\/revisions"}],"predecessor-version":[{"id":103589,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/posts\/103585\/revisions\/103589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media\/103590"}],"wp:attachment":[{"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/media?parent=103585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/categories?post=103585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitodo.com.mx\/wp\/wp-json\/wp\/v2\/tags?post=103585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}